{"id":889,"date":"2024-01-05T15:33:27","date_gmt":"2024-01-05T15:33:27","guid":{"rendered":"https:\/\/tecseal.es\/sr2-e\/"},"modified":"2024-03-19T14:39:10","modified_gmt":"2024-03-19T14:39:10","slug":"sr2-e","status":"publish","type":"post","link":"https:\/\/tecseal.es\/en\/sr2-e\/","title":{"rendered":"SR2\/E"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"889\" class=\"elementor elementor-889 elementor-321\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8495806 e-flex e-con-boxed e-con e-child\" data-id=\"8495806\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b13e85 elementor-widget elementor-widget-text-editor\" data-id=\"4b13e85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>TOLERANCES SR2E<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da666c2 elementor-widget elementor-widget-text-editor\" data-id=\"da666c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>SR2E: STAR BASE<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>TOLERANCES SR2E SR2E: STAR BASE<\/p>\n","protected":false},"author":1,"featured_media":685,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[41,35],"tags":[],"class_list":["post-889","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-extrusion-en","category-products"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SR2\/E - Tecseal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tecseal.es\/en\/sr2-e\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SR2\/E - Tecseal\" \/>\n<meta property=\"og:description\" content=\"TOLERANCES SR2E SR2E: STAR BASE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tecseal.es\/en\/sr2-e\/\" \/>\n<meta property=\"og:site_name\" content=\"Tecseal\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-05T15:33:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-19T14:39:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tecseal.es\/wp-content\/uploads\/2024\/01\/10006.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"910\" \/>\n\t<meta property=\"og:image:height\" content=\"575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tecseal.es\\\/en\\\/sr2-e\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecseal.es\\\/en\\\/sr2-e\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/tecseal.es\\\/#\\\/schema\\\/person\\\/baca599df2c01ec89a97da3dfb6f1f6f\"},\"headline\":\"SR2\\\/E\",\"datePublished\":\"2024-01-05T15:33:27+00:00\",\"dateModified\":\"2024-03-19T14:39:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tecseal.es\\\/en\\\/sr2-e\\\/\"},\"wordCount\":9,\"publisher\":{\"@id\":\"https:\\\/\\\/tecseal.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tecseal.es\\\/en\\\/sr2-e\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecseal.es\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/10006.jpg\",\"articleSection\":[\"Extrusion\",\"Products\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tecseal.es\\\/en\\\/sr2-e\\\/\",\"url\":\"https:\\\/\\\/tecseal.es\\\/en\\\/sr2-e\\\/\",\"name\":\"SR2\\\/E - Tecseal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecseal.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tecseal.es\\\/en\\\/sr2-e\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tecseal.es\\\/en\\\/sr2-e\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecseal.es\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/10006.jpg\",\"datePublished\":\"2024-01-05T15:33:27+00:00\",\"dateModified\":\"2024-03-19T14:39:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tecseal.es\\\/en\\\/sr2-e\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tecseal.es\\\/en\\\/sr2-e\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/tecseal.es\\\/en\\\/sr2-e\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tecseal.es\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/10006.jpg\",\"contentUrl\":\"https:\\\/\\\/tecseal.es\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/10006.jpg\",\"width\":910,\"height\":575},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tecseal.es\\\/en\\\/sr2-e\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/tecseal.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SR2\\\/E\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tecseal.es\\\/#website\",\"url\":\"https:\\\/\\\/tecseal.es\\\/\",\"name\":\"Tecseal\",\"description\":\"BURLETES DE ESTANQUIEDAD\",\"publisher\":{\"@id\":\"https:\\\/\\\/tecseal.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tecseal.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tecseal.es\\\/#organization\",\"name\":\"Tecseal\",\"url\":\"https:\\\/\\\/tecseal.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/tecseal.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tecseal.es\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo_tecseal.png\",\"contentUrl\":\"https:\\\/\\\/tecseal.es\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logo_tecseal.png\",\"width\":2695,\"height\":2695,\"caption\":\"Tecseal\"},\"image\":{\"@id\":\"https:\\\/\\\/tecseal.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tecseal.es\\\/#\\\/schema\\\/person\\\/baca599df2c01ec89a97da3dfb6f1f6f\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48b761bfc32435a8240c59da666d63732dbcc1a9953c4e7a4e7d6ceb44daee93?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48b761bfc32435a8240c59da666d63732dbcc1a9953c4e7a4e7d6ceb44daee93?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/48b761bfc32435a8240c59da666d63732dbcc1a9953c4e7a4e7d6ceb44daee93?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/tecseal.es\"],\"url\":\"https:\\\/\\\/tecseal.es\\\/en\\\/author\\\/avannubo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SR2\/E - Tecseal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tecseal.es\/en\/sr2-e\/","og_locale":"en_US","og_type":"article","og_title":"SR2\/E - Tecseal","og_description":"TOLERANCES SR2E SR2E: STAR BASE","og_url":"https:\/\/tecseal.es\/en\/sr2-e\/","og_site_name":"Tecseal","article_published_time":"2024-01-05T15:33:27+00:00","article_modified_time":"2024-03-19T14:39:10+00:00","og_image":[{"width":910,"height":575,"url":"https:\/\/tecseal.es\/wp-content\/uploads\/2024\/01\/10006.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tecseal.es\/en\/sr2-e\/#article","isPartOf":{"@id":"https:\/\/tecseal.es\/en\/sr2-e\/"},"author":{"name":"admin","@id":"https:\/\/tecseal.es\/#\/schema\/person\/baca599df2c01ec89a97da3dfb6f1f6f"},"headline":"SR2\/E","datePublished":"2024-01-05T15:33:27+00:00","dateModified":"2024-03-19T14:39:10+00:00","mainEntityOfPage":{"@id":"https:\/\/tecseal.es\/en\/sr2-e\/"},"wordCount":9,"publisher":{"@id":"https:\/\/tecseal.es\/#organization"},"image":{"@id":"https:\/\/tecseal.es\/en\/sr2-e\/#primaryimage"},"thumbnailUrl":"https:\/\/tecseal.es\/wp-content\/uploads\/2024\/01\/10006.jpg","articleSection":["Extrusion","Products"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/tecseal.es\/en\/sr2-e\/","url":"https:\/\/tecseal.es\/en\/sr2-e\/","name":"SR2\/E - Tecseal","isPartOf":{"@id":"https:\/\/tecseal.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tecseal.es\/en\/sr2-e\/#primaryimage"},"image":{"@id":"https:\/\/tecseal.es\/en\/sr2-e\/#primaryimage"},"thumbnailUrl":"https:\/\/tecseal.es\/wp-content\/uploads\/2024\/01\/10006.jpg","datePublished":"2024-01-05T15:33:27+00:00","dateModified":"2024-03-19T14:39:10+00:00","breadcrumb":{"@id":"https:\/\/tecseal.es\/en\/sr2-e\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tecseal.es\/en\/sr2-e\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tecseal.es\/en\/sr2-e\/#primaryimage","url":"https:\/\/tecseal.es\/wp-content\/uploads\/2024\/01\/10006.jpg","contentUrl":"https:\/\/tecseal.es\/wp-content\/uploads\/2024\/01\/10006.jpg","width":910,"height":575},{"@type":"BreadcrumbList","@id":"https:\/\/tecseal.es\/en\/sr2-e\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/tecseal.es\/"},{"@type":"ListItem","position":2,"name":"SR2\/E"}]},{"@type":"WebSite","@id":"https:\/\/tecseal.es\/#website","url":"https:\/\/tecseal.es\/","name":"Tecseal","description":"BURLETES DE ESTANQUIEDAD","publisher":{"@id":"https:\/\/tecseal.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tecseal.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/tecseal.es\/#organization","name":"Tecseal","url":"https:\/\/tecseal.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tecseal.es\/#\/schema\/logo\/image\/","url":"https:\/\/tecseal.es\/wp-content\/uploads\/2024\/01\/logo_tecseal.png","contentUrl":"https:\/\/tecseal.es\/wp-content\/uploads\/2024\/01\/logo_tecseal.png","width":2695,"height":2695,"caption":"Tecseal"},"image":{"@id":"https:\/\/tecseal.es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tecseal.es\/#\/schema\/person\/baca599df2c01ec89a97da3dfb6f1f6f","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/48b761bfc32435a8240c59da666d63732dbcc1a9953c4e7a4e7d6ceb44daee93?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/48b761bfc32435a8240c59da666d63732dbcc1a9953c4e7a4e7d6ceb44daee93?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/48b761bfc32435a8240c59da666d63732dbcc1a9953c4e7a4e7d6ceb44daee93?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/tecseal.es"],"url":"https:\/\/tecseal.es\/en\/author\/avannubo\/"}]}},"_links":{"self":[{"href":"https:\/\/tecseal.es\/en\/wp-json\/wp\/v2\/posts\/889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tecseal.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tecseal.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tecseal.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tecseal.es\/en\/wp-json\/wp\/v2\/comments?post=889"}],"version-history":[{"count":4,"href":"https:\/\/tecseal.es\/en\/wp-json\/wp\/v2\/posts\/889\/revisions"}],"predecessor-version":[{"id":2026,"href":"https:\/\/tecseal.es\/en\/wp-json\/wp\/v2\/posts\/889\/revisions\/2026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tecseal.es\/en\/wp-json\/wp\/v2\/media\/685"}],"wp:attachment":[{"href":"https:\/\/tecseal.es\/en\/wp-json\/wp\/v2\/media?parent=889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tecseal.es\/en\/wp-json\/wp\/v2\/categories?post=889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tecseal.es\/en\/wp-json\/wp\/v2\/tags?post=889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}